{"id":20136,"date":"2022-09-14T11:22:38","date_gmt":"2022-09-14T09:22:38","guid":{"rendered":"https:\/\/francescoeconomy.org\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/"},"modified":"2022-09-14T12:28:16","modified_gmt":"2022-09-14T10:28:16","slug":"the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco","status":"publish","type":"post","link":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/","title":{"rendered":"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"2560\" height=\"853\" title=\"EOF BANNER (1)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-scaled.jpg\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-scaled.jpg\" alt class=\"lazyload img-responsive wp-image-20130\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%27853%27%20viewBox%3D%270%200%202560%20853%27%3E%3Crect%20width%3D%272560%27%20height%3D%27853%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-200x67.jpg 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-400x133.jpg 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-600x200.jpg 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-800x267.jpg 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-1200x400.jpg 1200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EOF-BANNER-1-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 1200px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h1 style=\"text-align: center;\"><b>Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco<\/b><\/h1>\n<p>por: <a href=\"https:\/\/www.avvenire.it\/economiacivile\/pagine\/le-nuove-mille-e-una-notte-con-le-storie-dei-giovani-di-economy-of-francesco\" target=\"_blank\" rel=\"noopener\">Avvenire<\/a>.<\/p>\n<h3 style=\"text-align: center;\"><strong>Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.<\/strong><\/h3>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"1080\" height=\"1080\" title=\"EoF POSTS (7)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-POSTS-7.png\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-POSTS-7.png\" alt class=\"lazyload img-responsive wp-image-20116\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271080%27%20height%3D%271080%27%20viewBox%3D%270%200%201080%201080%27%3E%3Crect%20width%3D%271080%27%20height%3D%271080%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-POSTS-7-200x200.png 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-POSTS-7-400x400.png 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-POSTS-7-600x600.png 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-POSTS-7-800x800.png 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-POSTS-7.png 1080w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_3_4 3_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:75%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.56%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.56%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p><b>Se acerca el evento mundial en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb, publicado por Vita e Pensiero con Avvenire, editado por Maria Gaglione y Marco Girardo, que recoge veinticuatro historias publicadas en Avvenire en estos dos a\u00f1os del gran movimiento deseado por Francisco.<\/b><\/p>\n<p><i><span style=\"font-weight: 400;\">El gran visir, que a pesar de s\u00ed mismo era el ministro de tal ferocidad, ten\u00eda dos hijas, la mayor de las cuales ten\u00eda el nombre de Scheherazade, y la otra Dinarzade. Un d\u00eda, cuando estaban juntos en una conversaci\u00f3n, Scheherazade le dijo: \u00abPadre, tengo en mente detener el curso de barbarie que el sult\u00e1n ejerce sobre las familias de esta ciudad. Quiero disipar el justo temor que tantas madres tienen de perder a sus hijas de una manera tan funesta\u00bb.<\/span><\/i><\/p>\n<p><b>Las mil y una noches<\/b><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\"><p><span style=\"font-weight: 400;\">El rey Shahriyar, traicionado por su esposa, se casa con una nueva mujer cada noche y a la ma\u00f1ana siguiente la mata. Hasta que Shahrazad, hija del visir, imagina una soluci\u00f3n: entretendr\u00e1 al rey todas las noches cont\u00e1ndole una nueva historia y posponiendo el final de la historia para la noche siguiente. La experiencia funciona, y al final de los \u00abmil\u00bb cuentos, el rey tambi\u00e9n olvid\u00f3 su odio por las mujeres. As\u00ed que Shahrazad salv\u00f3 a las mujeres del pa\u00eds y se salv\u00f3 a s\u00ed misma simplemente encontrando una nueva historia para contar cada noche. <\/span><i><span style=\"font-weight: 400;\">Ars narrandi<\/span><\/i><span style=\"font-weight: 400;\">, <\/span><i><span style=\"font-weight: 400;\">ars vivendi<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La narrativa es entonces tambi\u00e9n un lugar al que ir para tratar de derrotar la muerte. En la tierra no s\u00f3lo hay una lucha perpetua entre <\/span><i><span style=\"font-weight: 400;\">eros<\/span><\/i><span style=\"font-weight: 400;\"> (amor) y <\/span><i><span style=\"font-weight: 400;\">tanatos<\/span><\/i><span style=\"font-weight: 400;\"> (muerte): hay una lucha a\u00fan m\u00e1s radical y decisiva entre <\/span><i><span style=\"font-weight: 400;\">tanatos<\/span><\/i><span style=\"font-weight: 400;\"> y <\/span><i><span style=\"font-weight: 400;\">logos<\/span><\/i><span style=\"font-weight: 400;\">, entre muerte y palabra, entre la muerte y las palabras. Mientras todav\u00eda tengamos algo que contarle a alguien, podemos posponer la llegada de la muerte por un d\u00eda y, tal vez, cuando llegue porque hemos terminado nuestra historia, descubriremos que todav\u00eda ten\u00edamos una historia que contar: era la \u00faltima, y era por ella.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las mujeres tienen una familiaridad particular con las palabras, porque tienen una intimidad especial con la vida. Tal vez porque durante milenios han custodiado la casa, y all\u00ed han desarrollado una de las relaciones primarias mientras los hombres se dedicaban a la econom\u00eda de las relaciones productivas y militares fuera del hogar. Cambiaron el mundo hablando, ense\u00f1ando a los ni\u00f1os a hablar, descifrando los susurros de los enfermos y los ancianos. Quiero pensar que fue idea de una mujer romana tener una diosa protectora de la \u00ableche de las madres\u00bb (<\/span><i><span style=\"font-weight: 400;\">dea edulica<\/span><\/i><span style=\"font-weight: 400;\">) y un dios protector de las \u00abprimeras palabras de los ni\u00f1os\u00bb (<\/span><i><span style=\"font-weight: 400;\">dio fabulinus<\/span><\/i><span style=\"font-weight: 400;\">), e incluso si los hombres los hubieran inventado, ciertamente habr\u00edan sido las madres quienes los invocaran. Si hoy, en una \u00e9poca de palabras desgastadas y cansadas, queremos redescubrir el significado del habla y de las palabras, tendremos que pedir a las mujeres que nos den las nuevas <\/span><i><span style=\"font-weight: 400;\">primeras palabras<\/span><\/i><span style=\"font-weight: 400;\"> necesarias.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"528\" height=\"363\" title=\"mateus-evento-eof-1\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27528%27%20height%3D%27363%27%20viewBox%3D%270%200%20528%20363%27%3E%3Crect%20width%3D%27528%27%20height%3D%27363%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/07\/mateus-evento-eof-1-e1663144179457.jpeg\" alt class=\"lazyload img-responsive wp-image-19274\"\/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4\"><p><span style=\"font-weight: 400;\">La Econom\u00eda de Francisco (EoF), que tom\u00f3 su nombre de dos hombres, Francisco de As\u00eds y el Papa Francisco, en realidad tambi\u00e9n tiene una dimensi\u00f3n femenina profunda y esencial. Hay muchas mujeres j\u00f3venes que se encuentran en este libro, hay muchas mujeres j\u00f3venes protagonistas de la EoF, y quien la encuentra siente la gracia y la graciosidad t\u00edpicas de las mujeres. Qui\u00e9n se encuentra con la EoF no encuentra poder sino deposi\u00f3n, pocos bienes econ\u00f3micos y muchos bienes relacionales, pocos capitales financieros y muchos capitales simb\u00f3licos, no ocupaci\u00f3n de espacios sino activaci\u00f3n de procesos&#8230; \u00bfy qui\u00e9n m\u00e1s que la que engendra un ni\u00f1o sabe lo que significa activar un proceso? Y cuando una casa es preparada y cuidada por mujeres, la casa es el <\/span><i><span style=\"font-weight: 400;\">oikos<\/span><\/i><span style=\"font-weight: 400;\"> de todos, su econom\u00eda se convierte en <\/span><i><span style=\"font-weight: 400;\">oikonomia<\/span><\/i><span style=\"font-weight: 400;\"> para el bien com\u00fan. El otro nombre de Francisco es Clara.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\"><p><span style=\"font-weight: 400;\">Al leer las historias de estos j\u00f3venes economistas, empresarios y agentes de cambio -\u2014las tres columnas de la EoF desde el principio\u2014, hay una fuerte impresi\u00f3n de estar en una nueva <\/span><i><span style=\"font-weight: 400;\">Mil y una noches<\/span><\/i><span style=\"font-weight: 400;\">, donde, incluso aqu\u00ed, cada historia termina en el comienzo de la siguiente historia. Diferentes caras y, sin embargo, una se disuelve en la otra, un hermoso poliedro con mil caras y, a diferencia de la esfera, un poliedro que conoces solo cuando has conocido todas las caras. Si te falta una, el poliedro no ha revelado su secreto. Por eso, la EoF, antes de ser un conjunto de ideas, de propuestas, de teor\u00edas econ\u00f3micas, es un mosaico de rostros, una comunidad abierta de <\/span><i><span style=\"font-weight: 400;\">personas<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Leyendo haces un aut\u00e9ntico recorrido por el mundo \u2014de norte a sur, de este a oeste\u2014 en la econom\u00eda del \u00abya\u00bb que se est\u00e1 anticipando a la econom\u00eda de lo que a\u00fan no se vislumbra en el horizonte. Historias y vocaciones, historias de vocaciones, de mujeres y hombres j\u00f3venes que escucharon una voz, que se sintieron llamados por su nombre al encontrarse con esa bendita carta del papa Francisco del 1 de mayo de 2019. Vocaciones que se convierten en un economista m\u00e9dica; microcr\u00e9ditos para mujeres en Uganda; la econom\u00eda local Inkiri; inclusi\u00f3n educativa en la India; gafas inteligentes japonesas; Olena, la estudiante ucraniana que sola es mensaje y grito; la lucha por los derechos de las mujeres en Mozambique; economistas e investigadores de la Academia EoF y la Escuela EoF que cuentan historias diferentes pero siempre maravillosas de mujeres y hombres j\u00f3venes que ya est\u00e1n cambiando el mundo persiguiendo una voz. Y est\u00e1n cambiando el mundo cambiando, cada d\u00eda, su econom\u00eda.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><img decoding=\"async\" width=\"1080\" height=\"1080\" title=\"EoF Academy (17)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-17.png\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-17.png\" alt class=\"lazyload img-responsive wp-image-17206\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271080%27%20height%3D%271080%27%20viewBox%3D%270%200%201080%201080%27%3E%3Crect%20width%3D%271080%27%20height%3D%271080%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-17-200x200.png 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-17-400x400.png 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-17-600x600.png 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-17-800x800.png 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-17.png 1080w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img decoding=\"async\" width=\"1080\" height=\"1080\" title=\"EoF Academy (12)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-12.png\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-12.png\" alt class=\"lazyload img-responsive wp-image-17189\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271080%27%20height%3D%271080%27%20viewBox%3D%270%200%201080%201080%27%3E%3Crect%20width%3D%271080%27%20height%3D%271080%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-12-200x200.png 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-12-400x400.png 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-12-600x600.png 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-12-800x800.png 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-12.png 1080w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-6 hover-type-none\"><img decoding=\"async\" width=\"1080\" height=\"1080\" title=\"EoF Academy (9)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-9.png\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-9.png\" alt class=\"lazyload img-responsive wp-image-17179\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271080%27%20height%3D%271080%27%20viewBox%3D%270%200%201080%201080%27%3E%3Crect%20width%3D%271080%27%20height%3D%271080%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-9-200x200.png 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-9-400x400.png 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-9-600x600.png 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-9-800x800.png 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-9.png 1080w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:7.68%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:7.68%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-7 hover-type-none\"><img decoding=\"async\" width=\"1080\" height=\"1080\" title=\"EoF Academy (16)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-16.png\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-16.png\" alt class=\"lazyload img-responsive wp-image-17202\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271080%27%20height%3D%271080%27%20viewBox%3D%270%200%201080%201080%27%3E%3Crect%20width%3D%271080%27%20height%3D%271080%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-16-200x200.png 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-16-400x400.png 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-16-600x600.png 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-16-800x800.png 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/03\/EoF-Academy-16.png 1080w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-6\"><p><span style=\"font-weight: 400;\">Cuando salimos llamados por Francisco, era antes de la pandemia y antes de la guerra en Ucrania. La crisis ambiental hab\u00eda estallado hace mucho tiempo, y un capitalismo desgastado y cansado ya estaba ante los ojos de muchos. El papa Francisco entendi\u00f3 que para \u00abdar nueva vida\u00bb a la econom\u00eda desahogada, para \u00abreconstruir una casa (<\/span><i><span style=\"font-weight: 400;\">oikos<\/span><\/i><span style=\"font-weight: 400;\">) que iba de camino a la ruina\u00bb, hab\u00eda que empezar por los j\u00f3venes. Fue una intuici\u00f3n maravillosa, y decisiva. Porque los j\u00f3venes tienen algunos recursos que est\u00e1n activos siempre y cuando seas joven.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La primera es la gratuidad. Los adultos tambi\u00e9n conocen y viven la gratuidad, porque forma parte del repertorio de lo humano. Pero mientras que en los adultos y los ancianos la gratuidad sobrevive si se sostiene por muchas virtudes y mucho dolor para derrotar la tendencia natural a la avaricia \u00e9tica y espiritual, el joven tiene una vocaci\u00f3n natural a la gratuidad. Para ellos, el dinero es demasiado poco: quieren todo, el mundo entero, el para\u00edso. Necesitan el dinero, por supuesto; a veces para ellos es muy importante incluso para vivir: pero lo usan como pista para su loco vuelo. Si quieres entender qu\u00e9 es realmente la gratuidad, que no tiene nada que ver con lo <\/span><i><span style=\"font-weight: 400;\">gratis<\/span><\/i><span style=\"font-weight: 400;\"> sino con la vida, mira a un joven.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n tienen una relaci\u00f3n muy especial con el infame \u00abprincipio de realidad\u00bb que en los adultos bloquea desde su nacimiento casi todos los proyectos grandes e innovadores. Ante la evidencia de que \u00abel mundo es as\u00ed\u00bb, los j\u00f3venes responden: \u00abVale, pero si no nos gusta, cambi\u00e9moslo\u00bb. Todav\u00eda somos j\u00f3venes hasta que ante un mundo que no nos gusta esperamos y pensamos que podemos cambiarlo. Cuando empezamos a decir \u00abesta es la realidad\u00bb y luego nos detenemos, la juventud ha terminado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por eso son antic\u00ednicos, creen en las grandes promesas de los amigos, son idealistas y concretos, con una concreci\u00f3n que incluye ideales y sue\u00f1os. Saben que la tierra prometida debe estar en alg\u00fan lugar, y nunca dejan de buscarla. Y saben so\u00f1ar, porque la juventud es el tiempo de grandes e infinitos sue\u00f1os.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un libro por tanto hecho de vida sola, historias vivas de so\u00f1adores a cada paso, que Mar\u00eda Gaglione y Marco Girardo, con los muchos periodistas de Avvenire han podido conocer, ver y luego narrar con mucho cuidado y atenci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Solo tengo que dar las gracias a los editores y a Avvenire y a la Editorial Vita e Pensiero.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Que el viento de la tierra sea mejor de lo que ha sido hasta ahora: que sostenga las grandes alas de estos j\u00f3venes, de todos los j\u00f3venes.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.<\/p>\n","protected":false},"author":3,"featured_media":20133,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[359,360,406,355,413,361,17,356,405,357,358],"tags":[],"class_list":["post-20136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eof-people-2-es","category-eof-people-es","category-eof-school-es","category-hubs-es","category-life-and-lifestyle-es","category-main-stage-posts-es","category-noticias","category-territories-es","category-villages-es","category-whats-on-es","category-whats-on-2-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco | The Economy of Francesco<\/title>\n<meta name=\"description\" content=\"Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco | The Economy of Francesco\" \/>\n<meta property=\"og:description\" content=\"Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/\" \/>\n<meta property=\"og:site_name\" content=\"The Economy of Francesco\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-14T09:22:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-14T10:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-Side-Site-7.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione EoF2020\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione EoF2020\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/\"},\"author\":{\"name\":\"Redazione EoF2020\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/0a4d32f78db94d19767e56c86230cbac\"},\"headline\":\"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco\",\"datePublished\":\"2022-09-14T09:22:38+00:00\",\"dateModified\":\"2022-09-14T10:28:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/\"},\"wordCount\":5252,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/EoF-Side-Site-7.png\",\"articleSection\":[\"EoF PEOPLE\",\"EoF PEOPLE\",\"EoF school\",\"HUBs\",\"Life and Lifestyle\",\"Main Stage\",\"Noticias\",\"Territories\",\"Villages\",\"WHAT&#8217;S ON\",\"WHAT&#8217;S ON\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/\",\"name\":\"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco | The Economy of Francesco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/EoF-Side-Site-7.png\",\"datePublished\":\"2022-09-14T09:22:38+00:00\",\"dateModified\":\"2022-09-14T10:28:16+00:00\",\"description\":\"Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/EoF-Side-Site-7.png\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/EoF-Side-Site-7.png\",\"width\":1024,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"name\":\"The Economy of Francesco\",\"description\":\"Young people, a commitment, the future\",\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francescoeconomy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\",\"name\":\"The Economy of Francesco\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"width\":513,\"height\":513,\"caption\":\"The Economy of Francesco\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/0a4d32f78db94d19767e56c86230cbac\",\"name\":\"Redazione EoF2020\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"caption\":\"Redazione EoF2020\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco | The Economy of Francesco","description":"Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/","og_locale":"es_ES","og_type":"article","og_title":"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco | The Economy of Francesco","og_description":"Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.","og_url":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/","og_site_name":"The Economy of Francesco","article_published_time":"2022-09-14T09:22:38+00:00","article_modified_time":"2022-09-14T10:28:16+00:00","og_image":[{"width":1024,"height":563,"url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-Side-Site-7.png","type":"image\/png"}],"author":"Redazione EoF2020","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redazione EoF2020","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#article","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/"},"author":{"name":"Redazione EoF2020","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/0a4d32f78db94d19767e56c86230cbac"},"headline":"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco","datePublished":"2022-09-14T09:22:38+00:00","dateModified":"2022-09-14T10:28:16+00:00","mainEntityOfPage":{"@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/"},"wordCount":5252,"commentCount":0,"publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"image":{"@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-Side-Site-7.png","articleSection":["EoF PEOPLE","EoF PEOPLE","EoF school","HUBs","Life and Lifestyle","Main Stage","Noticias","Territories","Villages","WHAT&#8217;S ON","WHAT&#8217;S ON"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/","url":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/","name":"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco | The Economy of Francesco","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#primaryimage"},"image":{"@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-Side-Site-7.png","datePublished":"2022-09-14T09:22:38+00:00","dateModified":"2022-09-14T10:28:16+00:00","description":"Se acerca el evento global en As\u00eds. Para entrar en la atm\u00f3sfera de la EoF, el prefacio de Luigino Bruni para el libro \u00abLa Econom\u00eda de Francisco. La historia de los protagonistas de una nueva econom\u00eda\u00bb.","breadcrumb":{"@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#primaryimage","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-Side-Site-7.png","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/EoF-Side-Site-7.png","width":1024,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/francescoeconomy.org\/es\/the-new-arabian-nights-with-the-stories-of-the-young-people-of-the-economy-of-francesco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/francescoeconomy.org\/es\/"},{"@type":"ListItem","position":2,"name":"Las nuevas Mil y una noches con las historias de los j\u00f3venes de la Econom\u00eda de Francisco"}]},{"@type":"WebSite","@id":"https:\/\/francescoeconomy.org\/#website","url":"https:\/\/francescoeconomy.org\/","name":"The Economy of Francesco","description":"Young people, a commitment, the future","publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francescoeconomy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/francescoeconomy.org\/#organization","name":"The Economy of Francesco","url":"https:\/\/francescoeconomy.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","width":513,"height":513,"caption":"The Economy of Francesco"},"image":{"@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/0a4d32f78db94d19767e56c86230cbac","name":"Redazione EoF2020","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","caption":"Redazione EoF2020"}}]}},"_links":{"self":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/20136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/comments?post=20136"}],"version-history":[{"count":0,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/20136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/media\/20133"}],"wp:attachment":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/media?parent=20136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/categories?post=20136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/tags?post=20136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}