{"id":20361,"date":"2022-09-21T18:01:36","date_gmt":"2022-09-21T16:01:36","guid":{"rendered":"https:\/\/francescoeconomy.org\/?p=20361"},"modified":"2022-09-21T18:01:36","modified_gmt":"2022-09-21T16:01:36","slug":"asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia","status":"publish","type":"post","link":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/","title":{"rendered":"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: \u00abGRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA\u00bb"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"225\" title=\"hw38w6\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/hw38w6.jpg\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/hw38w6-300x225.jpg\" alt class=\"lazyload img-responsive wp-image-20337\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271024%27%20height%3D%27768%27%20viewBox%3D%270%200%201024%20768%27%3E%3Crect%20width%3D%271024%27%20height%3D%27768%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/hw38w6-200x150.jpg 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/hw38w6-400x300.jpg 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/hw38w6-600x450.jpg 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/hw38w6-800x600.jpg 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/hw38w6.jpg 1024w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"200\" title=\"IMG_1554\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554.jpeg\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554-300x200.jpeg\" alt class=\"lazyload img-responsive wp-image-20340\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271280%27%20height%3D%27853%27%20viewBox%3D%270%200%201280%20853%27%3E%3Crect%20width%3D%271280%27%20height%3D%27853%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554-200x133.jpeg 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554-400x267.jpeg 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554-600x400.jpeg 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554-800x533.jpeg 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554-1200x800.jpeg 1200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG_1554.jpeg 1280w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.88%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>La ciudad est\u00e1 preparada para acoger al millar de j\u00f3venes economistas, emprendedores y agentes del cambio que estar\u00e1n en As\u00eds del 22 al 24 de septiembre para celebrar su compromiso com\u00fan de cambiar la econom\u00eda que culminar\u00e1, el s\u00e1bado 24 de septiembre, con la firma de un pacto con el Papa Francisco. Los tres d\u00edas de la EoF (The Economy of Francesco) se desarrollar\u00e1n entre el teatro Lyrick y el Pala eventi de Santa Maria degli Angeli y el centro hist\u00f3rico de As\u00eds, en 12 \u201cAldeas\u201d, en relaci\u00f3n con los temas que los j\u00f3venes han trabajado en los \u00faltimos tres a\u00f1os. \u00abPor fin estamos aqu\u00ed: gracias y bienvenidos los j\u00f3venes a La Econom\u00eda de Francisco\u00bb, dicen los miembros del comit\u00e9 organizador. Estamos seguros de que, aqu\u00ed en As\u00eds, podr\u00e9is sentir la espiritualidad franciscana y permitirnos conocer y apreciar los frutos de vuestro trabajo, que formar\u00e1n los cimientos de esta nueva econom\u00eda que el Santo Padre nos ha llamado a construir\u00bb.<\/p>\n<p><strong>EL PROGRAMA<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Un programa repleto de actividades e iniciativas\u00a0 para La Econom\u00eda de Francisco, que finalmente tendr\u00e1 lugar en presencia: a las 9.30 horas del <u>22 de septiembre<\/u> en el Lyrick la apertura del evento y la cosecha de la EoF (The Economy of Francesco): los j\u00f3venes se reunir\u00e1n con sesiones, debates y mesas redondas para presentar ideas y proyectos, abordar cuestiones econ\u00f3micas y desaf\u00edos contempor\u00e1neos. A continuaci\u00f3n, \u00abLa \u00fanica guerra justa es la que no libramos\u00bb, una reflexi\u00f3n sobre la prevenci\u00f3n de los conflictos armados. A partir de las 11.30 horas en el Pala eventi: EoF (The Economy of Francesco) Hogar, un espacio de encuentro y di\u00e1logo, por la tarde a las 17 horas la sesi\u00f3n plenaria con los embajadores de EoF con Vandana Shiva, Jeffrey Sachs, Kate Raworth, Gael Giraud, Sabina Alkire, Sister Helen Alford, Vilson Groh, Stefano Zamagni y Leonardo Becchetti. A continuaci\u00f3n, se pondr\u00e1 en escena la representaci\u00f3n de los j\u00f3venes del Instituto Ser\u00e1fico de As\u00eds \u00abEl sue\u00f1o\u00bb.<\/p>\n<p><u>Viernes 23<\/u> a las 9 h. Cara a cara con Francisco &#8211; Caminos tras las huellas de San Francisco (visitas a lugares relacionados con la vida del Santo), seguido a las 11 h. por el encuentro de los j\u00f3venes participantes en los distintas aldeas tem\u00e1ticas. A las 18.00 horas se celebrar\u00e1n conferencias abiertas a todo el mundo con j\u00f3venes economistas y empresarios que dialogar\u00e1n con ponentes internacionales sobre los principales temas del evento. En la Pro Civitate Christiana el economista Gael Giraud hablar\u00e1 sobre el tema \u00abLa econom\u00eda de Francisco: una nueva econom\u00eda construida por los j\u00f3venes\u00bb, en el Sacro Convento Francesco Sylos Labini sobre \u00abMeritocracia, evaluaci\u00f3n, excelencia: el caso de las universidades y la investigaci\u00f3n\u00bb, en el Monte Frumentario Vandana Shiva hablar\u00e1 sobre \u00abEconom\u00eda del cuidado, econom\u00eda del regalo. Reflexiones sobre San Francisco: &#8216;S\u00f3lo dando recibimos'\u00bb, en la Sala della Conciliazione Vilson Groh abordar\u00e1 el tema \u00abCaminos para un nuevo pacto educativo y econ\u00f3mico: construyendo puentes entre el centro y la periferia\u00bb. Y de nuevo en el Instituto Ser\u00e1fico la Hna. Helen Alford abordar\u00e1 el tema \u00abLa fraternidad universal: una idea que podr\u00eda cambiar el mundo\u00bb, en la Bas\u00edlica de Santa Maria degli Angeli el economista Stefano Zamagni hablar\u00e1 sobre \u00abLos peligros, ya evidentes, de la gerencializaci\u00f3n de la sociedad\u00bb. \u00bfCu\u00e1l es la contraestrategia?\u00bb. Por la noche, a las 21 horas, visitas guiadas a la Bas\u00edlica de San Francisco y a la Bas\u00edlica de Santa Mar\u00eda de los \u00c1ngeles.<\/p>\n<p>El evento de tres d\u00edas concluye, <u>el s\u00e1bado 2<\/u>4 de septiembre, con el encuentro de los participantes con el Papa en el teatro Lyrick, donde se firmar\u00e1 el Pacto por la Juventud. El encuentro ser\u00e1 retransmitido en directo por Rai Uno, en streaming en el canal YouTube de EoF (The Economy of Francesco) y en Vatican News en siete idiomas, adem\u00e1s del lenguaje de signos. El d\u00eda 22 tambi\u00e9n se transmitir\u00e1 en las mismas plataformas.<\/p>\n<p><strong>\u00abALDEAS\u00bb EN LUGARES FRANCISCANOS Y EN EL MONASTERIO DE SANTA CLARA<\/strong><\/p>\n<p>Como se ha mencionado, hay 12 \u00abALDEAS\u00bb (grupos de trabajo tem\u00e1ticos) en La Econom\u00eda de Francisco (EoF The Economy of Francesco), entre el centro hist\u00f3rico y Santa Maria degli Angeli. Tambi\u00e9n abrir\u00e1n sus puertas al p\u00fablico lugares especiales, como el Protomonasterio de Santa Chiara, que acoger\u00e1 la aldea La econom\u00eda es una mujer, y Monte Frumentario con Agricultura y Justicia y Finanzas y Humanidad. Vida y estilos de vida y Trabajo y cuidados ser\u00e1n acogidos en la Bas\u00edlica Papal y en el Sacro Convento di San Francesco, Vocaci\u00f3n y beneficio en el Santuario del Desnudo, Gesti\u00f3n y don en la Bas\u00edlica Santa Maria degli Angeli, Pol\u00edtica para la felicidad en el Archivo Episcopal de San Rufino, Empresa y paz en la Pro Civitate Christiana, Energ\u00eda y pobreza en el Palazzo del Comune, Empresas en transici\u00f3n en el Centro Pastoral Santa Maria degli Angeli y CO2 de la desigualdad en el Instituto Serafico.<\/p>\n<p><strong>PASES DE PRENSA, TRANSPORTE y M\u00c1S\u00a0 INFORMACI\u00d3N \u00daTIL PARA LA PRENSA<\/strong><\/p>\n<p>Ser\u00e1 posible recoger los pases de acreditaci\u00f3n en As\u00eds, a partir del 21 de septiembre de 2022, en el Teatro Lyrick, v\u00eda Gabriele D&#8217;Annunzio en Santa Maria degli Angeli, de 11.30 a 17.00 horas; los d\u00edas 22 y 23 de septiembre de 9 a 12 horas. El 24 de septiembre, desde las 8.00 hasta las 8.50 horas, a partir de esa hora ya no se podr\u00e1 acceder a la zona.<\/p>\n<p>El centro de prensa tendr\u00e1 el siguiente horario de apertura: del 21 al 23 de septiembre de 2022 de 10 a 19 horas; el 24 de septiembre de 2022 de 8 a 19 horas. Todo el material producido (textos, fotos y v\u00eddeos) estar\u00e1 disponible en el enlace: <a href=\"https:\/\/bit.ly\/3qQGQPQ\">https:\/\/bit.ly\/3qQGQPQ<\/a> .<br \/>\n( Se recomienda el uso de una m\u00e1scara en el centro de prensa.)<\/p>\n<p>El 24 de septiembre, el acceso a la zona reservada a los periodistas en la plaza frente al teatro Lyrick tendr\u00e1 que hacerse a pie desde la calle Antonio Fogazzaro (entrada a la piscina municipal). Se recomienda el aparcamiento Saba (gratuito) cerca de la estaci\u00f3n de tren (v\u00eda Giosu\u00e8 Borsi). Para viajar entre As\u00eds y Santa Maria degli Angeli ser\u00e1 posible utilizar las lanzaderas proporcionadas por Busitalia durante los tres d\u00edas del evento, simplemente mostrando su pase de \u00abPrensa\u00bb.<\/p>\n<p><strong>PERSONAS DE CONTACTO<\/strong><\/p>\n<p><u>Responsable de la estructura de informaci\u00f3n: <\/u><\/p>\n<p><u><br \/>\n<\/u>Marina Rosati (+39 339 637 8067, correo electr\u00f3nico: marina.rosati1974@gmail.com)<\/p>\n<p><u>Contactos para la prensa: <\/u><\/p>\n<p><u>\u00a0<\/u><\/p>\n<p>Flavia Pagliochini (+39 339 1709738, pgflavia@gmail.com- <a href=\"mailto:press@francescoeconomy.org\">press@francescoeconomy.org<\/a>)<\/p>\n<p>Antonella Porzi ( +39 3392067935), <a href=\"mailto:antonellaporzi@libero.it\">antonellaporzi@libero.it<\/a>)<\/p>\n<p>Marta Isabel Gonz\u00e1lez \u00c1lvarez (+34 646783686, <a href=\"mailto:press@francescoeconomy.org\">press@francescoeconomy.org<\/a>) (Espa\u00f1ol\/Italiano\/Ingl\u00e9s)<\/p>\n<p><strong>Assisi, 21 settembre 2022<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,357,358],"tags":[],"class_list":["post-20361","post","type-post","status-publish","format-standard","hentry","category-noticias","category-whats-on-es","category-whats-on-2-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: &quot;GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA&quot; | The Economy of Francesco<\/title>\n<meta name=\"description\" content=\"La ciudad est\u00e1 preparada para acoger al millar de j\u00f3venes economistas, emprendedores y agentes del cambio que estar\u00e1n en As\u00eds del 22 al 24 de septiembre para celebrar su compromiso com\u00fan de cambiar la econom\u00eda que culminar\u00e1, el s\u00e1bado 24 de septiembre, con la firma de un pacto con el Papa Francisco. Los tres d\u00edas de la EoF (The Economy of Francesco) se desarrollar\u00e1n entre el teatro Lyrick y el Pala eventi de Santa Maria degli Angeli y el centro hist\u00f3rico de As\u00eds, en 12 \u201cAldeas\u201d, en relaci\u00f3n con los temas que los j\u00f3venes han trabajado en los \u00faltimos tres a\u00f1os. &quot;Por fin estamos aqu\u00ed: gracias y bienvenidos los j\u00f3venes a La Econom\u00eda de Francisco&quot;, dicen los miembros del comit\u00e9 organizador. Estamos seguros de que, aqu\u00ed en As\u00eds, podr\u00e9is sentir la espiritualidad franciscana y permitirnos conocer y apreciar los frutos de vuestro trabajo, que formar\u00e1n los cimientos de esta nueva econom\u00eda que el Santo Padre nos ha llamado a construir&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: &quot;GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA&quot; | The Economy of Francesco\" \/>\n<meta property=\"og:description\" content=\"La ciudad est\u00e1 preparada para acoger al millar de j\u00f3venes economistas, emprendedores y agentes del cambio que estar\u00e1n en As\u00eds del 22 al 24 de septiembre para celebrar su compromiso com\u00fan de cambiar la econom\u00eda que culminar\u00e1, el s\u00e1bado 24 de septiembre, con la firma de un pacto con el Papa Francisco. Los tres d\u00edas de la EoF (The Economy of Francesco) se desarrollar\u00e1n entre el teatro Lyrick y el Pala eventi de Santa Maria degli Angeli y el centro hist\u00f3rico de As\u00eds, en 12 \u201cAldeas\u201d, en relaci\u00f3n con los temas que los j\u00f3venes han trabajado en los \u00faltimos tres a\u00f1os. &quot;Por fin estamos aqu\u00ed: gracias y bienvenidos los j\u00f3venes a La Econom\u00eda de Francisco&quot;, dicen los miembros del comit\u00e9 organizador. Estamos seguros de que, aqu\u00ed en As\u00eds, podr\u00e9is sentir la espiritualidad franciscana y permitirnos conocer y apreciar los frutos de vuestro trabajo, que formar\u00e1n los cimientos de esta nueva econom\u00eda que el Santo Padre nos ha llamado a construir&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/\" \/>\n<meta property=\"og:site_name\" content=\"The Economy of Francesco\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-21T16:01:36+00:00\" \/>\n<meta name=\"author\" content=\"Marta Isabel Gonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Isabel Gonzalez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/\"},\"author\":{\"name\":\"Marta Isabel Gonzalez\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/2e1d6d3ad3b6cbf9b862cacd05d63f7c\"},\"headline\":\"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: \u00abGRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA\u00bb\",\"datePublished\":\"2022-09-21T16:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/\"},\"wordCount\":2194,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"articleSection\":[\"Noticias\",\"WHAT&#8217;S ON\",\"WHAT&#8217;S ON\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/\",\"name\":\"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: \\\"GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA\\\" | The Economy of Francesco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\"},\"datePublished\":\"2022-09-21T16:01:36+00:00\",\"description\":\"La ciudad est\u00e1 preparada para acoger al millar de j\u00f3venes economistas, emprendedores y agentes del cambio que estar\u00e1n en As\u00eds del 22 al 24 de septiembre para celebrar su compromiso com\u00fan de cambiar la econom\u00eda que culminar\u00e1, el s\u00e1bado 24 de septiembre, con la firma de un pacto con el Papa Francisco. Los tres d\u00edas de la EoF (The Economy of Francesco) se desarrollar\u00e1n entre el teatro Lyrick y el Pala eventi de Santa Maria degli Angeli y el centro hist\u00f3rico de As\u00eds, en 12 \u201cAldeas\u201d, en relaci\u00f3n con los temas que los j\u00f3venes han trabajado en los \u00faltimos tres a\u00f1os. \\\"Por fin estamos aqu\u00ed: gracias y bienvenidos los j\u00f3venes a La Econom\u00eda de Francisco\\\", dicen los miembros del comit\u00e9 organizador. Estamos seguros de que, aqu\u00ed en As\u00eds, podr\u00e9is sentir la espiritualidad franciscana y permitirnos conocer y apreciar los frutos de vuestro trabajo, que formar\u00e1n los cimientos de esta nueva econom\u00eda que el Santo Padre nos ha llamado a construir\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: &#8220;GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"name\":\"The Economy of Francesco\",\"description\":\"Young people, a commitment, the future\",\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francescoeconomy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\",\"name\":\"The Economy of Francesco\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"width\":513,\"height\":513,\"caption\":\"The Economy of Francesco\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/2e1d6d3ad3b6cbf9b862cacd05d63f7c\",\"name\":\"Marta Isabel Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g\",\"caption\":\"Marta Isabel Gonzalez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: \"GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA\" | The Economy of Francesco","description":"La ciudad est\u00e1 preparada para acoger al millar de j\u00f3venes economistas, emprendedores y agentes del cambio que estar\u00e1n en As\u00eds del 22 al 24 de septiembre para celebrar su compromiso com\u00fan de cambiar la econom\u00eda que culminar\u00e1, el s\u00e1bado 24 de septiembre, con la firma de un pacto con el Papa Francisco. Los tres d\u00edas de la EoF (The Economy of Francesco) se desarrollar\u00e1n entre el teatro Lyrick y el Pala eventi de Santa Maria degli Angeli y el centro hist\u00f3rico de As\u00eds, en 12 \u201cAldeas\u201d, en relaci\u00f3n con los temas que los j\u00f3venes han trabajado en los \u00faltimos tres a\u00f1os. \"Por fin estamos aqu\u00ed: gracias y bienvenidos los j\u00f3venes a La Econom\u00eda de Francisco\", dicen los miembros del comit\u00e9 organizador. Estamos seguros de que, aqu\u00ed en As\u00eds, podr\u00e9is sentir la espiritualidad franciscana y permitirnos conocer y apreciar los frutos de vuestro trabajo, que formar\u00e1n los cimientos de esta nueva econom\u00eda que el Santo Padre nos ha llamado a construir\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/","og_locale":"es_ES","og_type":"article","og_title":"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: \"GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA\" | The Economy of Francesco","og_description":"La ciudad est\u00e1 preparada para acoger al millar de j\u00f3venes economistas, emprendedores y agentes del cambio que estar\u00e1n en As\u00eds del 22 al 24 de septiembre para celebrar su compromiso com\u00fan de cambiar la econom\u00eda que culminar\u00e1, el s\u00e1bado 24 de septiembre, con la firma de un pacto con el Papa Francisco. Los tres d\u00edas de la EoF (The Economy of Francesco) se desarrollar\u00e1n entre el teatro Lyrick y el Pala eventi de Santa Maria degli Angeli y el centro hist\u00f3rico de As\u00eds, en 12 \u201cAldeas\u201d, en relaci\u00f3n con los temas que los j\u00f3venes han trabajado en los \u00faltimos tres a\u00f1os. \"Por fin estamos aqu\u00ed: gracias y bienvenidos los j\u00f3venes a La Econom\u00eda de Francisco\", dicen los miembros del comit\u00e9 organizador. Estamos seguros de que, aqu\u00ed en As\u00eds, podr\u00e9is sentir la espiritualidad franciscana y permitirnos conocer y apreciar los frutos de vuestro trabajo, que formar\u00e1n los cimientos de esta nueva econom\u00eda que el Santo Padre nos ha llamado a construir\".","og_url":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/","og_site_name":"The Economy of Francesco","article_published_time":"2022-09-21T16:01:36+00:00","author":"Marta Isabel Gonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Isabel Gonzalez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/#article","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/"},"author":{"name":"Marta Isabel Gonzalez","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/2e1d6d3ad3b6cbf9b862cacd05d63f7c"},"headline":"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: \u00abGRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA\u00bb","datePublished":"2022-09-21T16:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/"},"wordCount":2194,"commentCount":0,"publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"articleSection":["Noticias","WHAT&#8217;S ON","WHAT&#8217;S ON"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/","url":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/","name":"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: \"GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA\" | The Economy of Francesco","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/#website"},"datePublished":"2022-09-21T16:01:36+00:00","description":"La ciudad est\u00e1 preparada para acoger al millar de j\u00f3venes economistas, emprendedores y agentes del cambio que estar\u00e1n en As\u00eds del 22 al 24 de septiembre para celebrar su compromiso com\u00fan de cambiar la econom\u00eda que culminar\u00e1, el s\u00e1bado 24 de septiembre, con la firma de un pacto con el Papa Francisco. Los tres d\u00edas de la EoF (The Economy of Francesco) se desarrollar\u00e1n entre el teatro Lyrick y el Pala eventi de Santa Maria degli Angeli y el centro hist\u00f3rico de As\u00eds, en 12 \u201cAldeas\u201d, en relaci\u00f3n con los temas que los j\u00f3venes han trabajado en los \u00faltimos tres a\u00f1os. \"Por fin estamos aqu\u00ed: gracias y bienvenidos los j\u00f3venes a La Econom\u00eda de Francisco\", dicen los miembros del comit\u00e9 organizador. Estamos seguros de que, aqu\u00ed en As\u00eds, podr\u00e9is sentir la espiritualidad franciscana y permitirnos conocer y apreciar los frutos de vuestro trabajo, que formar\u00e1n los cimientos de esta nueva econom\u00eda que el Santo Padre nos ha llamado a construir\".","breadcrumb":{"@id":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/francescoeconomy.org\/es\/asis-lista-para-recibir-al-papa-y-a-mil-participantes-el-comite-a-los-jovenes-gracias-por-estar-aqui-para-construir-una-nueva-economia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/francescoeconomy.org\/es\/"},{"@type":"ListItem","position":2,"name":"AS\u00cdS LISTA PARA RECIBIR AL PAPA Y A MIL PARTICIPANTES, EL COMIT\u00c9 A LOS J\u00d3VENES: &#8220;GRACIAS POR ESTAR AQU\u00cd PARA CONSTRUIR UNA NUEVA ECONOM\u00cdA&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/francescoeconomy.org\/#website","url":"https:\/\/francescoeconomy.org\/","name":"The Economy of Francesco","description":"Young people, a commitment, the future","publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francescoeconomy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/francescoeconomy.org\/#organization","name":"The Economy of Francesco","url":"https:\/\/francescoeconomy.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","width":513,"height":513,"caption":"The Economy of Francesco"},"image":{"@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/2e1d6d3ad3b6cbf9b862cacd05d63f7c","name":"Marta Isabel Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g","caption":"Marta Isabel Gonzalez"}}]}},"_links":{"self":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/20361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/comments?post=20361"}],"version-history":[{"count":0,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/20361\/revisions"}],"wp:attachment":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/media?parent=20361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/categories?post=20361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/tags?post=20361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}