{"id":20485,"date":"2022-09-23T20:12:20","date_gmt":"2022-09-23T18:12:20","guid":{"rendered":"https:\/\/francescoeconomy.org\/?p=20485"},"modified":"2022-09-23T20:39:59","modified_gmt":"2022-09-23T18:39:59","slug":"20485","status":"publish","type":"post","link":"https:\/\/francescoeconomy.org\/es\/20485\/","title":{"rendered":"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR  EL PACTO CON EL PAPA"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.333333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-carousel fusion-image-carousel-fixed fusion-image-carousel-1 fusion-carousel-border\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"no\" data-autoplayspeed=\"2500\" data-autoplaypause=\"no\" data-columns=\"5\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"13\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"fixed\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-border-width:1px;--awb-border-color:#e9eaee;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"\" alt=\"\"\/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271600%27%20height%3D%271200%27%20viewBox%3D%270%200%201600%201200%27%3E%3Crect%20width%3D%271600%27%20height%3D%271200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-blog-medium size-blog-medium lazyload\" alt=\"\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0143-320x202.jpg\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271600%27%20height%3D%271200%27%20viewBox%3D%270%200%201600%201200%27%3E%3Crect%20width%3D%271600%27%20height%3D%271200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-blog-medium size-blog-medium lazyload\" alt=\"\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0142-320x202.jpg\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271600%27%20height%3D%271200%27%20viewBox%3D%270%200%201600%201200%27%3E%3Crect%20width%3D%271600%27%20height%3D%271200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-blog-medium size-blog-medium lazyload\" alt=\"\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0141-320x202.jpg\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271824%27%20height%3D%271368%27%20viewBox%3D%270%200%201824%201368%27%3E%3Crect%20width%3D%271824%27%20height%3D%271368%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-blog-medium size-blog-medium lazyload\" alt=\"\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0137-320x202.jpg\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"320\" height=\"202\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272048%27%20height%3D%271536%27%20viewBox%3D%270%200%202048%201536%27%3E%3Crect%20width%3D%272048%27%20height%3D%271536%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" class=\"attachment-blog-medium size-blog-medium lazyload\" alt=\"\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0104-320x202.jpg\" \/><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.88%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h1><strong><em>Para recibir al Pont\u00edfice cinco j\u00f3venes que representan a los cinco continentes<\/em><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<h1><strong><em>LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR<br \/>\nEL PACTO CON EL PAPA<\/em><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<h1><strong><em>El programa de la jornada en la que los participantes en la EoF celebran su compromiso com\u00fan de cambiar la econom\u00eda<\/em><\/strong><\/h1>\n<p>El Papa Francisco llega a As\u00eds ma\u00f1ana s\u00e1bado 24 de septiembre: es el d\u00eda en el que mil j\u00f3venes economistas, empresarios y <em>changemakers<\/em> celebrar\u00e1n su compromiso com\u00fan para cambiar la econom\u00eda con la firma de un pacto con el Pont\u00edfice que, por un lado, marca el final de un largo proceso de preparaci\u00f3n y, por otro, el inicio de un proceso de cambio concreto que parte de la base.<\/p>\n<p><strong>EL PROGRAMA DE LA VISITA DEL PAPA<\/strong><\/p>\n<p>A las 9.00 horas, el helic\u00f3ptero que transportar\u00e1 al Papa despegar\u00e1 del helipuerto vaticano, para aterrizar media hora m\u00e1s tarde en una zona frente al Pala Eventi (al lado del teatro Lyric) de Santa Maria degli Angeli. El Santo Padre llegar\u00e1 a la explanada frente al teatro Lyrick, donde ser\u00e1 recibido por Monse\u00f1or Domenico Sorrentino Obispo de As\u00eds, Nocera\u00a0 Umbra, Gualdo Tadino y de Foligno, Presidente del Comit\u00e9 Organizador, y por cinco j\u00f3venes representantes de los cinco continentes (Argentina, Sri Lanka, Noruega, Mozambique y Nueva Zelanda) en representaci\u00f3n de todos los j\u00f3venes participantes en EoF y en este evento; por el Card. Michael Czerny, Prefecto del Dicasterio para el Servicio del Desarrollo Humano Integral; Sor Alessandra Smerilli FMA, secretaria del mismo Dicasterio vaticano\u00a0 (colaborador de este evento y que apoya la comunidad de The Economy of Francesco \u2013 EoF); Donatella Tesei, Presidenta de la Regi\u00f3n de Umbr\u00eda; el Responsable de la Seguridad de Perugia, Armando Gradone; \u00a0Stefania Proietti, Alcaldesa de As\u00eds y Presidenta de la Provincia de Perugia; los representantes de las familias franciscanas; los miembros del Comit\u00e9 Promotor del evento: Luigino Bruni, Francesca di Maolo, \u00a0el presidente de Pro Civitate Christiana, Don Tonio Dell&#8217;Olio y por el presidente de la Fundaci\u00f3n Santuario de la Desposesi\u00f3n, Don Cesare Provenzi.\u00a0 A las 10 de la ma\u00f1ana el Santo Padre llegar\u00e1 al escenario para el encuentro con los j\u00f3venes, que incluir\u00e1 un momento art\u00edstico-teatral basado en el <em>verso \u00abCentinela \u00bfcu\u00e1nto queda de la noche?\u00bb<\/em> (Is 21,11), una bienvenida e introducci\u00f3n, y la narraci\u00f3n de experiencias por parte de ocho j\u00f3venes: un estudiante italiano de doctorado en Econom\u00eda, un argentino, un africano, una joven adolescente de Tailandia, un economista mas\u00e1i de Kenia, una joven afgana activista de los derechos de la mujer en su pa\u00eds, un agricultor y cofundador de <em>The Farm of Francesco<\/em> y un joven preso y estudiante de f\u00edsica que hablar\u00e1 del valor del trabajo en su vida dentro de la c\u00e1rcel.<\/p>\n<p>A continuaci\u00f3n, el discurso del Santo Padre y a las 11.30 h, al final del encuentro, el Papa firmar\u00e1 el \u201cPacto con los j\u00f3venes\u201d, que incluye los doce compromisos elaborados al final del viernes, jornada de trabajo en las Aldeas tem\u00e1ticas de The Economy of Francesco. A continuaci\u00f3n, el Santo Padre llegar\u00e1 a la plaza donde ha aterrizado el helic\u00f3ptero y desde donde, tras un cuarto de hora, despegar\u00e1 de Santa Maria degli Angeli.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>EL C\u00c1NTARO \u00a0DEL INSTITUTO SER\u00c1FICO<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Bajo el escenario del teatro Lyrick habr\u00e1 un c\u00e1ntaro decorado por los j\u00f3venes con diversas discapacidades del Instituto Ser\u00e1fico de As\u00eds y que recoger\u00e1 los compromisos de los j\u00f3venes ante el Papa Francisco. Es un c\u00e1ntaro inspirado en los que durante el episodio evang\u00e9lico de \u201cLas Bodas de Can\u00e1\u201d vivieron la transformaci\u00f3n del agua en vino por Jesucristo, que supuso, adem\u00e1s, el primer milagro realizado en su vida p\u00fablica y recogido por el Evangelio y con \u00e9l el inicio de un camino de profundo cambio para toda la humanidad.<\/p>\n<p>Este c\u00e1ntaro fue cambiado de color por los j\u00f3venes del Instituto Ser\u00e1fico finalmente estamparon sus manos en \u00e9l: los chicos se convirtieron en verdaderos artistas, capaces de transmitir lo que est\u00e1 en el coraz\u00f3n del arte mismo: un mensaje para una nueva visi\u00f3n de la sociedad en la que, incluso la voz de los m\u00e1s fr\u00e1giles y descartados de la sociedad, se convierte en un recurso para el crecimiento de todas las personas.<\/p>\n<p>El c\u00e1ntaro se colocar\u00e1 en el jard\u00edn de la \u201cPorci\u00fancula,\u201d en recuerdo del lugar desde el que partieron en misi\u00f3n los primeros frailes, tras las huellas de San Francisco de As\u00eds. La esperanza -para los participantes- es que las ideas y propuestas de los j\u00f3venes de EoF puedan iniciar un aut\u00e9ntico cambio para nuestra sociedad y su econom\u00eda, introduciendo una nueva visi\u00f3n en la que el crecimiento no sea s\u00f3lo el de los beneficios, sino el de la vida de todos.<\/p>\n<p><strong>EL RESUMEN D\u00cdA DEL VIERNES 23 DE SEPTIEMBRE<\/strong><\/p>\n<p>Mientras tanto, el viernes 23 de septiembre de 2022 fue el d\u00eda de la visita a los lugares franciscanos. Los j\u00f3venes colorearon la ciudad ser\u00e1fica con sus pases y su alegr\u00eda durante A tu per tu con Francesco &#8211; Percorsi sulle orme di San Francesco (Cara a cara con Francisco &#8211; Caminos tras las huellas de San Francisco) y durante las conferencias en las \u201cAldeas\u201d (grupos de trabajo tem\u00e1ticos), instaladas en el interior de Santa Maria degli Angeli y en el centro hist\u00f3rico de As\u00eds. Momentos de encuentro y di\u00e1logo en el Protomonasterio de Santa Clara (\u201cLa econom\u00eda es una mujer\u201d), en el Monte Frumentario (\u201cAgricultura y Justicia\u201d y \u201cFinanzas y Humanidad\u201d), Bas\u00edlica Papal y Sacro Convento de San Francisco (\u201cVida y Estilos de Vida\u201d y \u201cTrabajo y Cuidados\u201d), en el Santuario del la Expoliaci\u00f3n (\u201cVocaci\u00f3n y Beneficios\u201d), en la Bas\u00edlica de Santa Maria degli Angeli (\u201cGesti\u00f3n y Don\u201d), en el Archivo Episcopal de San Rufino (\u201cPol\u00edtica para la Felicidad\u201d), en el Pro Civitate Christiana (\u201cEmpresas y Paz\u201d), en el Ayuntamiento (\u201cEnerg\u00eda y Pobreza\u201d), en el Instituto Serafico de As\u00eds (\u201cCO2 de la Desigualdad\u201d) y en el Centro Pastoral de Santa Maria degli Angeli (\u201cEmpresas en Transici\u00f3n\u201d).<\/p>\n<p>A continuaci\u00f3n, los j\u00f3venes se reunieron con ponentes internacionales sobre los principales temas del evento. En la Pro Civitate Christiana el economista Gael Giraud que habl\u00f3 sobre el tema \u00abLa econom\u00eda de Francisco: una nueva econom\u00eda construida por los j\u00f3venes\u00bb, en el Sacro Convento Francesco Sylos Labini sobre \u00abMeritocracia, evaluaci\u00f3n, excelencia: el caso de las universidades y la investigaci\u00f3n\u00bb, en el Monte Frumentario la activista Vandana Shiva que ha hablado sobre \u00abEconom\u00eda del cuidado, econom\u00eda del don. Reflexiones sobre San Francisco: &#8216;S\u00f3lo dando recibimos'\u00bb, en la Sala della Conciliazione de As\u00eds, Vilson Groh ha abordado el tema \u00abCaminos para un nuevo pacto educativo y econ\u00f3mico: construyendo puentes entre el centro y la periferia\u00bb. Y de nuevo en el Instituto Serafico, la hermana Helen Alford ha abordado el tema \u00abLa fraternidad universal: una idea que podr\u00eda cambiar el mundo\u00bb, en la Bas\u00edlica de Santa Maria degli Angeli, el economista Stefano Zamagni ha hablado sobre el tema \u00abLos peligros, ya evidentes, de la gerencializaci\u00f3n de la sociedad\u00bb. \u00bfCu\u00e1l es la contraestrategia?\u00bb. Y esta noche, a las 21 horas, habr\u00e1 visitas guiadas a la Bas\u00edlica de San Francisco y a la Bas\u00edlica de Santa Mar\u00eda de los \u00c1ngeles.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>PERSONAS DE CONTACTO<\/strong><\/p>\n<p><u>Responsable de la estructura de informaci\u00f3n: <\/u><\/p>\n<p><u><br \/>\n<\/u>Marina Rosati (+39 339 637 8067, correo electr\u00f3nico: marina.rosati1974@gmail.com)<\/p>\n<p><u>Contactos para la prensa: <\/u><\/p>\n<p><u>\u00a0<\/u><\/p>\n<p>Flavia Pagliochini (+39 339 1709738, pgflavia@gmail.com- <a href=\"mailto:press@francescoeconomy.org\">press@francescoeconomy.org<\/a>)<\/p>\n<p>Antonella Porzi ( +39 3392067935), <a href=\"mailto:antonellaporzi@libero.it\">antonellaporzi@libero.it<\/a>)<\/p>\n<p>Marta Isabel Gonz\u00e1lez \u00c1lvarez (+34 646783686, <a href=\"mailto:press@francescoeconomy.org\">press@francescoeconomy.org<\/a>) (Espa\u00f1ol\/Italiano\/Ingl\u00e9s)<\/p>\n<p>Todos los materiales interesantes para la prensa (textos, fotos y videos) est\u00e1n a vuestra disposici\u00f3n en el siguiente link:\u00a0<a href=\"https:\/\/bit.ly\/3qQGQPQ\">https:\/\/bit.ly\/3qQGQPQ<\/a>.<\/p>\n<p><strong>Assisi, 23 settembre 2022<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":20469,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,357,358],"tags":[],"class_list":["post-20485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-whats-on-es","category-whats-on-2-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA | The Economy of Francesco<\/title>\n<meta name=\"description\" content=\"Para recibir al Pont\u00edfice cinco j\u00f3venes que representan a los cinco continentes LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPAEl programa de la jornada en la que los participantes en la EoF celebran su compromiso com\u00fan de cambiar la econom\u00eda- El Papa Francisco llega a As\u00eds ma\u00f1ana s\u00e1bado 24 de septiembre: es el d\u00eda en el que mil j\u00f3venes economistas, empresarios y changemakers celebrar\u00e1n su compromiso com\u00fan para cambiar la econom\u00eda con la firma de un pacto con el Pont\u00edfice que, por un lado, marca el final de un largo proceso de preparaci\u00f3n y, por otro, el inicio de un proceso de cambio concreto que parte de la base.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francescoeconomy.org\/es\/20485\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA | The Economy of Francesco\" \/>\n<meta property=\"og:description\" content=\"Para recibir al Pont\u00edfice cinco j\u00f3venes que representan a los cinco continentes LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPAEl programa de la jornada en la que los participantes en la EoF celebran su compromiso com\u00fan de cambiar la econom\u00eda- El Papa Francisco llega a As\u00eds ma\u00f1ana s\u00e1bado 24 de septiembre: es el d\u00eda en el que mil j\u00f3venes economistas, empresarios y changemakers celebrar\u00e1n su compromiso com\u00fan para cambiar la econom\u00eda con la firma de un pacto con el Pont\u00edfice que, por un lado, marca el final de un largo proceso de preparaci\u00f3n y, por otro, el inicio de un proceso de cambio concreto que parte de la base.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francescoeconomy.org\/es\/20485\/\" \/>\n<meta property=\"og:site_name\" content=\"The Economy of Francesco\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T18:12:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-23T18:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0104.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta Isabel Gonzalez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta Isabel Gonzalez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/\"},\"author\":{\"name\":\"Marta Isabel Gonzalez\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/2e1d6d3ad3b6cbf9b862cacd05d63f7c\"},\"headline\":\"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA\",\"datePublished\":\"2022-09-23T18:12:20+00:00\",\"dateModified\":\"2022-09-23T18:39:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/\"},\"wordCount\":2289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220923-WA0104.jpg\",\"articleSection\":[\"Noticias\",\"WHAT&#8217;S ON\",\"WHAT&#8217;S ON\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/\",\"name\":\"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA | The Economy of Francesco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220923-WA0104.jpg\",\"datePublished\":\"2022-09-23T18:12:20+00:00\",\"dateModified\":\"2022-09-23T18:39:59+00:00\",\"description\":\"Para recibir al Pont\u00edfice cinco j\u00f3venes que representan a los cinco continentes LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPAEl programa de la jornada en la que los participantes en la EoF celebran su compromiso com\u00fan de cambiar la econom\u00eda- El Papa Francisco llega a As\u00eds ma\u00f1ana s\u00e1bado 24 de septiembre: es el d\u00eda en el que mil j\u00f3venes economistas, empresarios y changemakers celebrar\u00e1n su compromiso com\u00fan para cambiar la econom\u00eda con la firma de un pacto con el Pont\u00edfice que, por un lado, marca el final de un largo proceso de preparaci\u00f3n y, por otro, el inicio de un proceso de cambio concreto que parte de la base.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#primaryimage\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220923-WA0104.jpg\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG-20220923-WA0104.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/20485\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"name\":\"The Economy of Francesco\",\"description\":\"Young people, a commitment, the future\",\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francescoeconomy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\",\"name\":\"The Economy of Francesco\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"width\":513,\"height\":513,\"caption\":\"The Economy of Francesco\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/2e1d6d3ad3b6cbf9b862cacd05d63f7c\",\"name\":\"Marta Isabel Gonzalez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g\",\"caption\":\"Marta Isabel Gonzalez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA | The Economy of Francesco","description":"Para recibir al Pont\u00edfice cinco j\u00f3venes que representan a los cinco continentes LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPAEl programa de la jornada en la que los participantes en la EoF celebran su compromiso com\u00fan de cambiar la econom\u00eda- El Papa Francisco llega a As\u00eds ma\u00f1ana s\u00e1bado 24 de septiembre: es el d\u00eda en el que mil j\u00f3venes economistas, empresarios y changemakers celebrar\u00e1n su compromiso com\u00fan para cambiar la econom\u00eda con la firma de un pacto con el Pont\u00edfice que, por un lado, marca el final de un largo proceso de preparaci\u00f3n y, por otro, el inicio de un proceso de cambio concreto que parte de la base.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francescoeconomy.org\/es\/20485\/","og_locale":"es_ES","og_type":"article","og_title":"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA | The Economy of Francesco","og_description":"Para recibir al Pont\u00edfice cinco j\u00f3venes que representan a los cinco continentes LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPAEl programa de la jornada en la que los participantes en la EoF celebran su compromiso com\u00fan de cambiar la econom\u00eda- El Papa Francisco llega a As\u00eds ma\u00f1ana s\u00e1bado 24 de septiembre: es el d\u00eda en el que mil j\u00f3venes economistas, empresarios y changemakers celebrar\u00e1n su compromiso com\u00fan para cambiar la econom\u00eda con la firma de un pacto con el Pont\u00edfice que, por un lado, marca el final de un largo proceso de preparaci\u00f3n y, por otro, el inicio de un proceso de cambio concreto que parte de la base.","og_url":"https:\/\/francescoeconomy.org\/es\/20485\/","og_site_name":"The Economy of Francesco","article_published_time":"2022-09-23T18:12:20+00:00","article_modified_time":"2022-09-23T18:39:59+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0104.jpg","type":"image\/jpeg"}],"author":"Marta Isabel Gonzalez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marta Isabel Gonzalez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francescoeconomy.org\/es\/20485\/#article","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/es\/20485\/"},"author":{"name":"Marta Isabel Gonzalez","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/2e1d6d3ad3b6cbf9b862cacd05d63f7c"},"headline":"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA","datePublished":"2022-09-23T18:12:20+00:00","dateModified":"2022-09-23T18:39:59+00:00","mainEntityOfPage":{"@id":"https:\/\/francescoeconomy.org\/es\/20485\/"},"wordCount":2289,"commentCount":0,"publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"image":{"@id":"https:\/\/francescoeconomy.org\/es\/20485\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0104.jpg","articleSection":["Noticias","WHAT&#8217;S ON","WHAT&#8217;S ON"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/francescoeconomy.org\/es\/20485\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/francescoeconomy.org\/es\/20485\/","url":"https:\/\/francescoeconomy.org\/es\/20485\/","name":"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA | The Economy of Francesco","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francescoeconomy.org\/es\/20485\/#primaryimage"},"image":{"@id":"https:\/\/francescoeconomy.org\/es\/20485\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0104.jpg","datePublished":"2022-09-23T18:12:20+00:00","dateModified":"2022-09-23T18:39:59+00:00","description":"Para recibir al Pont\u00edfice cinco j\u00f3venes que representan a los cinco continentes LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPAEl programa de la jornada en la que los participantes en la EoF celebran su compromiso com\u00fan de cambiar la econom\u00eda- El Papa Francisco llega a As\u00eds ma\u00f1ana s\u00e1bado 24 de septiembre: es el d\u00eda en el que mil j\u00f3venes economistas, empresarios y changemakers celebrar\u00e1n su compromiso com\u00fan para cambiar la econom\u00eda con la firma de un pacto con el Pont\u00edfice que, por un lado, marca el final de un largo proceso de preparaci\u00f3n y, por otro, el inicio de un proceso de cambio concreto que parte de la base.","breadcrumb":{"@id":"https:\/\/francescoeconomy.org\/es\/20485\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francescoeconomy.org\/es\/20485\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/francescoeconomy.org\/es\/20485\/#primaryimage","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0104.jpg","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2022\/09\/IMG-20220923-WA0104.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/francescoeconomy.org\/es\/20485\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/francescoeconomy.org\/es\/"},{"@type":"ListItem","position":2,"name":"LOS J\u00d3VENES de THE ECONOMY OF FRANCESCO LISTOS PARA FIRMAR EL PACTO CON EL PAPA"}]},{"@type":"WebSite","@id":"https:\/\/francescoeconomy.org\/#website","url":"https:\/\/francescoeconomy.org\/","name":"The Economy of Francesco","description":"Young people, a commitment, the future","publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francescoeconomy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/francescoeconomy.org\/#organization","name":"The Economy of Francesco","url":"https:\/\/francescoeconomy.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","width":513,"height":513,"caption":"The Economy of Francesco"},"image":{"@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/2e1d6d3ad3b6cbf9b862cacd05d63f7c","name":"Marta Isabel Gonzalez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20577a3c6195b29e32edcbb7163b1a467bb4e244f6acb3a1323e57f7831f0c82?s=96&d=mm&r=g","caption":"Marta Isabel Gonzalez"}}]}},"_links":{"self":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/20485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/comments?post=20485"}],"version-history":[{"count":0,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/20485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/media\/20469"}],"wp:attachment":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/media?parent=20485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/categories?post=20485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/tags?post=20485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}