{"id":24576,"date":"2023-09-30T20:55:38","date_gmt":"2023-09-30T18:55:38","guid":{"rendered":"https:\/\/francescoeconomy.org\/?p=24576"},"modified":"2023-10-02T13:39:20","modified_gmt":"2023-10-02T11:39:20","slug":"generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis","status":"publish","type":"post","link":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/","title":{"rendered":"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h3 style=\"text-align: center;\">La <em>generaci\u00f3n de EoF<\/em> lista para el IV encuentro mundial online con el mensaje del Papa<\/h3>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:45;line-height:1.5;\"><p style=\"text-align: center;\">The Economy of Francesco, reuni\u00f3n mundial el 6 de octubre en directo desde As\u00eds<\/p><\/h1><\/div><div class=\"fusion-text fusion-text-2\"><h4>Ideas, historias y proyectos, en conexi\u00f3n con 30 pa\u00edses. Evento presencial en el Santuario de la Spogliazione para los italianos<\/h4>\n<\/div><div class=\"fusion-text fusion-text-3\"><p><strong>AS\u00cdS (ITALIA)<\/strong> &#8211; El pr\u00f3ximo 6 de octubre a las 4.00 p.m. (CEST) los j\u00f3venes economistas, agentes de cambio y emprendedores del mundo se reunir\u00e1n online para celebrar el IV encuentro anual de The Economy of Francesco &#8211; La Econom\u00eda de Francisco (EoF). \u201c\u00a1Esto lo digo en serio: cuento con ustedes!\u00a0 &#8211; les hab\u00eda dicho el Papa Francisco salud\u00e1ndolos en As\u00eds en el 2022 -. Por favor, no nos dejen tranquilos, denos el ejemplo!\u201d. La invitaci\u00f3n fue acogida por la <em>generaci\u00f3n EoF<\/em> que sigue trabajando con seriedad y responsabilidad sin descuidar nada de lo que hoy preocupa y exige un cambio urgente. Desigualdades, econom\u00eda ind\u00edgena, trabajo, paz, seguridad alimentaria, crisis ambiental, sistemas financieros, pero tambi\u00e9n capitales narrativos y espirituales, estos son algunos de los temas centrales de la agenda EoF.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1024\" height=\"1024\" title=\"eof23-wa (1)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1-1024x1024.jpg\" alt class=\"lazyload img-responsive wp-image-24563\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271080%27%20height%3D%271080%27%20viewBox%3D%270%200%201080%201080%27%3E%3Crect%20width%3D%271080%27%20height%3D%271080%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1-200x200.jpg 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1-400x400.jpg 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1-600x600.jpg 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1-800x800.jpg 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg 1080w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4\"><p>El economista turco <strong>Daron Acemoglu<\/strong>, es invitado del evento, entre otros. Es profesor de econom\u00eda en la MIT de Boston, en di\u00e1logo con la EoF Academy. Los intereses de sus investigaciones van de la teor\u00eda del crecimiento a la econom\u00eda del trabajo, de la desigualdad en la distribuci\u00f3n de las ganancias a la matem\u00e1tica aplicada. El impacto de la tecnolog\u00eda en las desigualdades y una reflexi\u00f3n sobre los puntos ciegos del saber econ\u00f3mico, ser\u00e1n las dos contribuciones principales de los j\u00f3venes estudiosos de la red acad\u00e9mica.<\/p>\n<p>Tambi\u00e9n se dedicar\u00e1 un amplio espacio al tema de la paz. Se prev\u00e9 una conexi\u00f3n con el tercer <em>Congreso Internacional de Econom\u00eda de Francisco, Am\u00e9rica Latina y Caribe<\/em>, a desarrollarse del 4 al 6 de octubre en Colombia, que tiene por t\u00edtulo: <em>Tejer econom\u00edas para la paz.<\/em><\/p>\n<p>La directa del evento titulado <em><strong>\u00abLa 25ta hora. EoF (on air) Global Gathering\u00bb<\/strong><\/em>, ser\u00e1 transmitida por el Instituto Ser\u00e1fico, con el formato de \u201cradio web\u201d, y estar\u00e1 disponible en directo, en varios idiomas, en el canal youtube de The Economy of Francesco. M\u00fasica, ideas, informaci\u00f3n, interacci\u00f3n a trav\u00e9s de las redes sociales: este a\u00f1o los j\u00f3venes que crearon el programa eligieron la radio como el lugar narrativo para dialogar y narrar historias, ideas, vocaciones y experiencias alcanzando a un amplio p\u00fablico, donde todas las voces pueden expresarse, ser representadas y escuchadas.<\/p>\n<p>Est\u00e1n previstas conexiones y contribuciones desde m\u00e1s de 30 pa\u00edses del mundo, momentos de meditaci\u00f3n sobre los pasos de Francisco de As\u00eds y una columna dedicada a personajes y fechas hist\u00f3ricas.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\"><p>La <em>\u00ab25ta hora\u00bb<\/em> ser\u00e1 el tema propuesto por el coordinador cient\u00edfico de EoF, el economista Luigino Bruni.<\/p>\n<p>Se espera la presentaci\u00f3n de las obras ganadoras del concurso <em>\u00abThe Stories we are\u00bb<\/em>, y una obra teatral titulada \u00ab<em>Pinocchio, elogio del cammino e del dono\u00bb (Pinocchio, elogio del camino y del don)<\/em> se presentar\u00e1 como lectura in\u00e9dita de un cl\u00e1sico de la literatura mundial.<\/p>\n<p>El encuentro terminar\u00e1 con un nuevo mensaje del Papa Francisco que este a\u00f1o se dirigiri\u00e1 nuevamente a los j\u00f3venes economistas y emprendedores de EoF.<\/p>\n<p>Para seguir en directo y para detalles del programa: <a href=\"http:\/\/www.francescoeconomy.org\" target=\"_blank\" rel=\"noopener\">www.francescoeconomy.org<\/a>.<\/p>\n<p>Adem\u00e1s del evento online, los referentes regionales de \u2018The Economy of Francesco Hub Italia\u2019, consideraron oportuno volver a proponer un momento de encuentro presencial en As\u00eds del 6 al 8 de octubre, bajo la ense\u00f1a de las relaciones y de la formaci\u00f3n. H\u00faespedes de la di\u00f3cesis de As\u00eds y puntualmente del Santuario de la Spogliazione, m\u00e1s de 70 partecipantes de La Econom\u00eda de Francisco (EoF) en Italia, se encontrar\u00e1n para profundizar temas econ\u00f3micos y sociales a trav\u00e9s de sesiones pensadas ad hoc para facilitar y compartir el intercambio de ideas.<\/p>\n<p><strong>As\u00eds, 30 de septiembre de 2023<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ideas, historias y proyectos, en conexi\u00f3n con 30 pa\u00edses. Evento presencial en el Santuario de la Spogliazione para los italianos.<\/p>\n","protected":false},"author":3,"featured_media":24563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,357],"tags":[449],"class_list":["post-24576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-whats-on-es","tag-event-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds | The Economy of Francesco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds | The Economy of Francesco\" \/>\n<meta property=\"og:description\" content=\"Ideas, historias y proyectos, en conexi\u00f3n con 30 pa\u00edses. Evento presencial en el Santuario de la Spogliazione para los italianos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/\" \/>\n<meta property=\"og:site_name\" content=\"The Economy of Francesco\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-30T18:55:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-02T11:39:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione EoF2020\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione EoF2020\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/\"},\"author\":{\"name\":\"Redazione EoF2020\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/0a4d32f78db94d19767e56c86230cbac\"},\"headline\":\"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds\",\"datePublished\":\"2023-09-30T18:55:38+00:00\",\"dateModified\":\"2023-10-02T11:39:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/\"},\"wordCount\":3728,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eof23-wa-1.jpg\",\"keywords\":[\"event\"],\"articleSection\":[\"Noticias\",\"WHAT&#8217;S ON\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/\",\"name\":\"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds | The Economy of Francesco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eof23-wa-1.jpg\",\"datePublished\":\"2023-09-30T18:55:38+00:00\",\"dateModified\":\"2023-10-02T11:39:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eof23-wa-1.jpg\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/eof23-wa-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/francescoeconomy.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"name\":\"The Economy of Francesco\",\"description\":\"Young people, a commitment, the future\",\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francescoeconomy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\",\"name\":\"The Economy of Francesco\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"width\":513,\"height\":513,\"caption\":\"The Economy of Francesco\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/0a4d32f78db94d19767e56c86230cbac\",\"name\":\"Redazione EoF2020\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"caption\":\"Redazione EoF2020\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds | The Economy of Francesco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/","og_locale":"es_ES","og_type":"article","og_title":"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds | The Economy of Francesco","og_description":"Ideas, historias y proyectos, en conexi\u00f3n con 30 pa\u00edses. Evento presencial en el Santuario de la Spogliazione para los italianos.","og_url":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/","og_site_name":"The Economy of Francesco","article_published_time":"2023-09-30T18:55:38+00:00","article_modified_time":"2023-10-02T11:39:20+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg","type":"image\/jpeg"}],"author":"Redazione EoF2020","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redazione EoF2020","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#article","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/"},"author":{"name":"Redazione EoF2020","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/0a4d32f78db94d19767e56c86230cbac"},"headline":"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds","datePublished":"2023-09-30T18:55:38+00:00","dateModified":"2023-10-02T11:39:20+00:00","mainEntityOfPage":{"@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/"},"wordCount":3728,"commentCount":0,"publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"image":{"@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg","keywords":["event"],"articleSection":["Noticias","WHAT&#8217;S ON"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/","url":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/","name":"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds | The Economy of Francesco","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#primaryimage"},"image":{"@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg","datePublished":"2023-09-30T18:55:38+00:00","dateModified":"2023-10-02T11:39:20+00:00","breadcrumb":{"@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#primaryimage","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/09\/eof23-wa-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/francescoeconomy.org\/es\/generacion-eof-lista-para-el-iv-encuentro-mundial-online-endirecto-desde-asis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/francescoeconomy.org\/es\/"},{"@type":"ListItem","position":2,"name":"La generaci\u00f3n de EoF lista para el IV encuentro mundial online, en directo desde As\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/francescoeconomy.org\/#website","url":"https:\/\/francescoeconomy.org\/","name":"The Economy of Francesco","description":"Young people, a commitment, the future","publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francescoeconomy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/francescoeconomy.org\/#organization","name":"The Economy of Francesco","url":"https:\/\/francescoeconomy.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","width":513,"height":513,"caption":"The Economy of Francesco"},"image":{"@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/0a4d32f78db94d19767e56c86230cbac","name":"Redazione EoF2020","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","caption":"Redazione EoF2020"}}]}},"_links":{"self":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/24576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/comments?post=24576"}],"version-history":[{"count":0,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/posts\/24576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/media\/24563"}],"wp:attachment":[{"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/media?parent=24576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/categories?post=24576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francescoeconomy.org\/es\/wp-json\/wp\/v2\/tags?post=24576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}