{"id":23832,"date":"2023-07-25T06:53:34","date_gmt":"2023-07-25T04:53:34","guid":{"rendered":"https:\/\/francescoeconomy.org\/the-stories-we-are\/"},"modified":"2023-07-26T19:56:39","modified_gmt":"2023-07-26T17:56:39","slug":"the-stories-we-are","status":"publish","type":"post","link":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/","title":{"rendered":"The stories we are"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h1 style=\"text-align: center;\"><b>The stories we are<\/b><\/h1>\n<h3><strong>Vivere le nostre storie<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Il capitale narrativo \u00e8 il frutto della dimensione narrativa degli esseri umani: in quanto <\/span><i><span style=\"font-weight: 400;\">homo sapiens<\/span><\/i><span style=\"font-weight: 400;\"> siamo anche <\/span><i><span style=\"font-weight: 400;\">homo narrans<\/span><\/i><span style=\"font-weight: 400;\"> \u2013 uomini e donne capaci di raccontare e di ascoltare storie. Anche all\u2019origine delle civilt\u00e0 umane troviamo racconti e miti che le hanno generate e rigenerate nei secoli e nei millenni. Per gli esseri umani, fatti e cifre non sono sufficienti: <\/span><b>abbiamo bisogno di parole<\/b><span style=\"font-weight: 400;\">; la realt\u00e0 non \u00e8 sufficiente: <\/span><b>vogliamo i sogni<\/b><span style=\"font-weight: 400;\"> e, per sognare ad occhi aperti, <\/span><b>abbiamo bisogno di storie<\/b><span style=\"font-weight: 400;\">. Il capitale narrativo comprende tradizioni, leggende, <\/span><span style=\"font-weight: 400;\">storie, poesie, canti <\/span><span style=\"font-weight: 400;\">tramandati nel tempo e tra le generazioni. Rappresenta,<\/span><span style=\"font-weight: 400;\"> quindi, un patrimonio \u2013 cio\u00e8\u00a0<\/span><i><span style=\"font-weight: 400;\">munus\u00a0<\/span><\/i><span style=\"font-weight: 400;\">\/dono dei\u00a0<\/span><i><span style=\"font-weight: 400;\">padri<\/span><\/i><span style=\"font-weight: 400;\"> ed \u00e8 un autentico\u00a0<\/span><i><span style=\"font-weight: 400;\">capitale<\/span><\/i><span style=\"font-weight: 400;\">\u00a0perch\u00e9, come tutti i capitali, genera frutti e futuro.\u00a0<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1080\" height=\"1080\" title=\"EoF (1)\" src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EoF-1-1.png\" data-orig-src=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EoF-1-1.png\" alt class=\"lazyload img-responsive wp-image-23822\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271080%27%20height%3D%271080%27%20viewBox%3D%270%200%201080%201080%27%3E%3Crect%20width%3D%271080%27%20height%3D%271080%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EoF-1-1-200x200.png 200w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EoF-1-1-400x400.png 400w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EoF-1-1-600x600.png 600w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EoF-1-1-800x800.png 800w, https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EoF-1-1.png 1080w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 720px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p><span style=\"font-weight: 400;\">Pensiamoci! \u2026 <\/span><span style=\"font-weight: 400;\">Alla radice dei momenti pi\u00f9 forti e importanti della nostra vita ci sono fatti ed esperienze che sono diventate storie che abbiamo raccontato ai nostri figli e loro ai nostri nipoti [o che abbiamo ascoltato dai nostri genitori o nonni] e ogni volta che li abbiamo raccontati [<\/span><span style=\"font-weight: 400;\">o ascoltati] <\/span><span style=\"font-weight: 400;\">li abbiamo capiti meglio, e un po\u2019 cambiati.\u00a0Anche all\u2019inizio di grandi esperienze collettive, ci sono <\/span><b>grandi narrazioni collettive<\/b><span style=\"font-weight: 400;\">. Comunit\u00e0, organizzazioni, imprese, movimenti (spirituali, culturali, sociali, politici) nascono se le azioni e le idee dei singoli e dei gruppi riescono a diventare storie. Senza riuscire a trasformare le esperienze in racconti, i fatti non diventano fenomeni sociali, restano fatti muti. Le imprese collettive iniziano mentre proviamo a raccontarle a qualcuno.<\/span><\/p>\n<h3><strong>Una rivoluzione narrativa<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Esiste un legame, poi, tra capitale narrativo e capitale spirituale. Il capitale spirituale &#8211; di una comunit\u00e0, di un popolo, di una cultura &#8211; comprende le dimensioni simboliche, morali e spirituali ereditate dalle generazioni precedenti. La nascita delle religioni, ad esempio, \u00e8 significativamente legata allo sviluppo dei linguaggi e quindi delle narrazioni. Il capitale narrativo e il capitale spirituale sono due forme di capitali fondamentali, che sono stati sempre &#8211; e devono restare &#8211; importanti per\u00a0affrontare le sfide di ogni tempo, compreso lo sviluppo economico e civile dei nostri paesi, il <\/span><i><span style=\"font-weight: 400;\">benesser<\/span><\/i><span style=\"font-weight: 400;\">e delle nostre societ\u00e0. Essi contribuiscono a costruire <\/span><b>la visione del mondo<\/b><span style=\"font-weight: 400;\"> che caratterizza e identifica in modo univoco una persona, un\u2019organizzazione, una comunit\u00e0, un Paese e il tessuto sociale che ne risulta ha un impatto significativo sulle persone con cui viviamo e sul modo in cui collaboriamo.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\"><p><span style=\"font-weight: 400;\">Quando questi capitali sono disponibili, le persone sono pi\u00f9 resilienti, hanno maggiori strumenti per affrontare le difficolt\u00e0 della vita e per poter \u201cfiorire\u201d, possono fare affidamento sull\u2019esperienza delle generazioni precedenti, lasciandosi ispirare da loro e sentendosi in \u201cbuona compagnia\u201d. Questi capitali, a cui gli scienziati sociali raramente hanno prestato attenzione, si stanno esaurendo rapidamente \u2013 senza vederne nascere nuovi &#8211; a causa dell\u2019aumento dell\u2019individualismo e del secolarismo delle nostre societ\u00e0, con conseguenze negative sulla sostenibilit\u00e0 anche dei nostri sistemi socio-economici.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Oggi, molte delle comunit\u00e0, cooperative, imprese e movimenti &#8211; fondati nel XX secolo &#8211; soffrono per una carestia di capitali narrativi: una gravissima crisi di storie e narrazioni capaci di attrarre, convincere, incantare come nei primi tempi della loro fondazione. Molte cose sono cambiate nel passaggio tra il XX e il XXI secolo. Tra queste, i codici narrativi con cui comunicare &#8211; tra generazioni &#8211; i fatti, i valori e le esperienze importanti. Pertanto la crisi delle religioni, delle fedi e dei grandi ideali, oggi \u00e8 fondamentalmente una crisi narrativa. Le persone, in particolare i giovani, non capiscono pi\u00f9 le grandi storie: quando cerchiamo di raccontarle, finiamo per &#8220;dire parole d&#8217;amore in una lingua morta&#8221;. Non sono i contenuti a non dire pi\u00f9 nulla, \u00e8 la nostra capacit\u00e0 di raccontarli che fa fatica. Il futuro delle religioni, della spiritualit\u00e0, degli ideali, delle virt\u00f9 etiche e civili dipende soprattutto da <\/span><b>una rivoluzione narrativa capace di ricostruire un nuovo capitale spirituale.<\/b><\/p>\n<h3><strong>The Economy of Francesco e un nuovo capitale narrativo<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Il linguaggio \u00e8 il primo segnale che dice la crisi antropologica, e quindi spirituale ed etica, che sta attraversando anche il mondo dell&#8217;economia e dell&#8217;impresa, oggi. Sappiamo bene che \u201cl&#8217;economia \u00e8 sempre stata pi\u00f9 grande dell&#8217;economia\u201d. E continua ad esserlo. Dietro il denaro, il lavoro, il consumo, il risparmio, l&#8217;impresa, non ci sono solo i bisogni e i gusti dei consumatori: ci sono i sogni, i desideri, le promesse, le passioni, lo spirito, le vocazioni che nascono dalla vita economica per indicare qualcosa che va oltre l\u2019economia. Perch\u00e9 l\u2019economia \u00e8 un universo di parole, simboli, segni: un codice per decifrare <\/span><b>la grammatica dell&#8217;anima<\/b><span style=\"font-weight: 400;\"> degli individui e delle societ\u00e0.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il mondo dell&#8217;economia, dell&#8217;impresa, della finanza, sono luoghi umani (perch\u00e9 abitati ancora da esseri umani!) dove pi\u00f9 forte \u00e8 la sofferenza per la carestia di parole <\/span><i><span style=\"font-weight: 400;\">vive e vere<\/span><\/i><span style=\"font-weight: 400;\">, da un lato, e per la grande quantit\u00e0 di <\/span><i><span style=\"font-weight: 400;\">chiacchiere<\/span><\/i><span style=\"font-weight: 400;\"> inutili, dall&#8217;altro: parole, frasi, espressioni troppo povere per dire bene le cose umane che accadono, slogan espressione di un pensiero unico che sta contribuendo alla perdita di biodiversit\u00e0 e generativit\u00e0.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. <\/span><i><span style=\"font-weight: 400;\">Restituire un&#8217;anima all&#8217;economia <\/span><\/i><span style=\"font-weight: 400;\">(Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative. La &#8220;missione&#8221; di EoF \u00e8 anche quella di offrire nuovi capitali narrativi, in economia, nelle scienze sociali, nella teologia, nella spiritualit\u00e0 &#8230; e in tanti altri ambiti della vita! E di far emergere creativit\u00e0, coraggio, capacit\u00e0 di attrarre nuovi giovani talenti e idee.\u00a0<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. Restituire un&#8217;anima all&#8217;economia (Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative.<\/p>\n","protected":false},"author":3,"featured_media":23829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[248,238,60,16,232,240],"tags":[],"class_list":["post-23832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eof-people-2-it","category-eof-people","category-main-stage-posts-it","category-notizie","category-whats-on-2","category-whats-on-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The stories we are | The Economy of Francesco<\/title>\n<meta name=\"description\" content=\"\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. Restituire un&#039;anima all&#039;economia (Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The stories we are | The Economy of Francesco\" \/>\n<meta property=\"og:description\" content=\"\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. Restituire un&#039;anima all&#039;economia (Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/\" \/>\n<meta property=\"og:site_name\" content=\"The Economy of Francesco\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T04:53:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-26T17:56:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EOF-2-1-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione EoF2020\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione EoF2020\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/\"},\"author\":{\"name\":\"Redazione EoF2020\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/0a4d32f78db94d19767e56c86230cbac\"},\"headline\":\"The stories we are\",\"datePublished\":\"2023-07-25T04:53:34+00:00\",\"dateModified\":\"2023-07-26T17:56:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/\"},\"wordCount\":3238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EOF-2-1.png\",\"articleSection\":[\"EoF PEOPLE\",\"EoF PEOPLE\",\"Main Stage\",\"Notizie\",\"WHAT'S ON\",\"WHAT&#8217;S ON\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/\",\"name\":\"The stories we are | The Economy of Francesco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EOF-2-1.png\",\"datePublished\":\"2023-07-25T04:53:34+00:00\",\"dateModified\":\"2023-07-26T17:56:39+00:00\",\"description\":\"\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. Restituire un'anima all'economia (Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#primaryimage\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EOF-2-1.png\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/EOF-2-1.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/the-stories-we-are\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/francescoeconomy.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The stories we are\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#website\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"name\":\"The Economy of Francesco\",\"description\":\"Young people, a commitment, the future\",\"publisher\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/francescoeconomy.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#organization\",\"name\":\"The Economy of Francesco\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"contentUrl\":\"https:\\\/\\\/francescoeconomy.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Logo-EoF2020-tracciato.png\",\"width\":513,\"height\":513,\"caption\":\"The Economy of Francesco\"},\"image\":{\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/francescoeconomy.org\\\/#\\\/schema\\\/person\\\/0a4d32f78db94d19767e56c86230cbac\",\"name\":\"Redazione EoF2020\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g\",\"caption\":\"Redazione EoF2020\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The stories we are | The Economy of Francesco","description":"\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. Restituire un'anima all'economia (Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/","og_locale":"it_IT","og_type":"article","og_title":"The stories we are | The Economy of Francesco","og_description":"\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. Restituire un'anima all'economia (Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative.","og_url":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/","og_site_name":"The Economy of Francesco","article_published_time":"2023-07-25T04:53:34+00:00","article_modified_time":"2023-07-26T17:56:39+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EOF-2-1-1024x576.png","type":"image\/png"}],"author":"Redazione EoF2020","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione EoF2020","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#article","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/"},"author":{"name":"Redazione EoF2020","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/0a4d32f78db94d19767e56c86230cbac"},"headline":"The stories we are","datePublished":"2023-07-25T04:53:34+00:00","dateModified":"2023-07-26T17:56:39+00:00","mainEntityOfPage":{"@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/"},"wordCount":3238,"commentCount":0,"publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"image":{"@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EOF-2-1.png","articleSection":["EoF PEOPLE","EoF PEOPLE","Main Stage","Notizie","WHAT'S ON","WHAT&#8217;S ON"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/","url":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/","name":"The stories we are | The Economy of Francesco","isPartOf":{"@id":"https:\/\/francescoeconomy.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#primaryimage"},"image":{"@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#primaryimage"},"thumbnailUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EOF-2-1.png","datePublished":"2023-07-25T04:53:34+00:00","dateModified":"2023-07-26T17:56:39+00:00","description":"\u00c8 necessario far rivivere le narrazioni spirituali ed etiche nel contesto della nostra contemporaneit\u00e0. Restituire un'anima all'economia (Papa Francesco, 2019) \u00e8 una sfida che richiede una nuova stagione di autentica spiritualit\u00e0, erede e continuatrice delle grandi narrative.","breadcrumb":{"@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#primaryimage","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EOF-2-1.png","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2023\/07\/EOF-2-1.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/francescoeconomy.org\/it\/the-stories-we-are\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/francescoeconomy.org\/it\/"},{"@type":"ListItem","position":2,"name":"The stories we are"}]},{"@type":"WebSite","@id":"https:\/\/francescoeconomy.org\/#website","url":"https:\/\/francescoeconomy.org\/","name":"The Economy of Francesco","description":"Young people, a commitment, the future","publisher":{"@id":"https:\/\/francescoeconomy.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francescoeconomy.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/francescoeconomy.org\/#organization","name":"The Economy of Francesco","url":"https:\/\/francescoeconomy.org\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/","url":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","contentUrl":"https:\/\/francescoeconomy.org\/wp-content\/uploads\/2019\/06\/Logo-EoF2020-tracciato.png","width":513,"height":513,"caption":"The Economy of Francesco"},"image":{"@id":"https:\/\/francescoeconomy.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/francescoeconomy.org\/#\/schema\/person\/0a4d32f78db94d19767e56c86230cbac","name":"Redazione EoF2020","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51c54530e7ca8d246384f0e18612ba96bd45ad0728553869a5bef56e89529ab9?s=96&d=mm&r=g","caption":"Redazione EoF2020"}}]}},"_links":{"self":[{"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/posts\/23832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/comments?post=23832"}],"version-history":[{"count":0,"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/posts\/23832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/media\/23829"}],"wp:attachment":[{"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/media?parent=23832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/categories?post=23832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francescoeconomy.org\/it\/wp-json\/wp\/v2\/tags?post=23832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}